{"id":2444,"date":"2024-11-07T10:25:10","date_gmt":"2024-11-07T10:25:10","guid":{"rendered":"https:\/\/igs-hf.org\/team-member\/debes-ty\/"},"modified":"2026-01-20T07:26:24","modified_gmt":"2026-01-20T07:26:24","slug":"debes-ty","status":"publish","type":"team-member","link":"https:\/\/igs-hf.org\/de\/teammitglied\/debes-ty\/","title":{"rendered":"Debes Ty"},"content":{"rendered":"\n<p> <\/p>\n","protected":false},"featured_media":9863,"template":"","meta":{"_acf_changed":true,"_gspb_post_css":""},"role-type":[29],"class_list":["post-2444","team-member","type-team-member","status-publish","has-post-thumbnail","hentry","role-type-primary-secondary","resize-featured-image"],"acf":{"first_name":"Ty","last_name":"Debes","chinese_name":"","role_category":false,"role_title":"Lehrer","headshot":9863,"contact_email":"ty.debes@igs-hf.org","bio":"In meiner Rolle als Lehrer f\u00fcr moderne Fremdsprachen unterrichte ich Franz\u00f6sisch und Spanisch an der International German School. Zudem besitze ich Erfahrung als Lehrkraft f\u00fcr Englisch. Aufgrund meiner zur\u00fcckliegenden T\u00e4tigkeit in verschiedenen Sprachabteilungen konzentriere ich mich auf die F\u00f6rderung der Mehrsprachigkeit sowie die Integration mehrerer Sprachen in den Schulalltag.\r\n\r\nMit acht Jahren Unterrichtserfahrung in f\u00fcnf L\u00e4ndern verf\u00fcge ich \u00fcber eine breite Perspektive und Expertise.","language_spoken":"gb, de, fr, es, ee, vn"},"_links":{"self":[{"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/team-member\/2444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/team-member"}],"about":[{"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/types\/team-member"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/media\/9863"}],"wp:attachment":[{"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/media?parent=2444"}],"wp:term":[{"taxonomy":"role-type","embeddable":true,"href":"https:\/\/igs-hf.org\/de\/wp-json\/wp\/v2\/role-type?post=2444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}